{"id":5771,"date":"2020-03-07T20:46:05","date_gmt":"2020-03-07T19:46:05","guid":{"rendered":"https:\/\/giessen.dakd.de\/?p=5771"},"modified":"2020-07-29T20:48:46","modified_gmt":"2020-07-29T18:48:46","slug":"wzs-07-03-2020","status":"publish","type":"post","link":"https:\/\/bremen.dakd.de\/am\/wzs-07-03-2020\/","title":{"rendered":"Wort am Sonntag am 07.03.2020"},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-fusion-600 wp-image-5603 alignnone\" src=\"http:\/\/giessen.dakd.de\/wp-content\/uploads\/2020\/07\/WortZumSonntag-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/p>\n<p><strong>Der dritte Sonntag der Gro\u00dfen Fastenzeit bezeichnet man in der armenischen Kirche als <\/strong><br \/>\n<strong>\u201eSonntag vom verlorenen Sohn\u201c und ist nur im Lukasevangelium zu finden. (L 15, 11-32).<\/strong><\/p>\n<p>In diesem Gleichnis erz\u00e4hlt uns Jesus, wie die S\u00fcnde einem Menschen das Leben verdirbt und dieser dann wieder zu seinem Vater zur\u00fcckfindet.<\/p>\n<p>Jesus ermahnt zur Reue und Bu\u00dfe und erz\u00e4hlt ein Gleichnis. Ein Mann hatte zwei S\u00f6hne. Der j\u00fcngste Sohn verlangt von seinem Vater sein Erbe und zieht in die Fremde. Er lebt in Saus und Braus und gibt das ganze Geld aus, so dass er am Ende Mittellos dasteht.<\/p>\n<p>In seinem Ungl\u00fcck gesteht er sich sein Fehlverhalten und beschlie\u00dft in Reue, nach Hause, zu seinem Vater zur\u00fcck zu kehren und ihm um Vergebung zu bitten. Als er noch weit weg war, sah ihn sein Vater und war voller Mitgef\u00fchl. Er rannte und umarmte seinen Sohn. Der Sohn sagte zu seinem Vater: \u201eVater, ich habe mich gegen den Himmel und gegen dich vers\u00fcndigt; ich bin nicht mehr wert, dein Sohn zu sein.\u201c (15, 21). Der Vater befahl seinen Knechten, dem Sohn das beste Gewand anzuziehen, ihm einen wertvollen Ring anzustecken und ihm Sandalen zu geben. \u201eBringt das Mastkalb her und schlachtet es; wir wollen essen und fr\u00f6hlich sein. Denn dieser, mein Sohn, war tot und lebt wieder; er war verloren und ist wiedergefunden worden\u201d <a href=\"https:\/\/www.bibleserver.com\/EU\/Lukas15%2C24\" class=\"bibleserver extern\" target=\"_blank\" rel=\"noopener noreferrer\">Lk 15,24<\/a><\/p>\n<p>Welche Lehre k\u00f6nnen wir aus diesem Gleichnis ziehen? Manchmal machen wir etwas falsch und entfernen uns von der g\u00f6ttlichen Liebe. Dann bereuen wir es und wollen unser Leben ver\u00e4ndern. Aber das Leben zu ver\u00e4ndern ist oft schwierig! Manchmal braucht es viel Mut, um zur\u00fcckzukehren, um Vergebung zu bitten und so den Weg zur Gemeinschaft zu finden. Dieses Gleichnis ermutigt uns, uns jederzeit in Reue und Demut zum himmlischen, liebevollen Vater zu wenden, der jeden mit offenen Armen aufnimmt.<\/p>\n<p>Yeghishe Vartabed Avetisyan<\/p>","protected":false},"excerpt":{"rendered":"<p>Der dritte Sonntag der Gro\u00dfen Fastenzeit bezeichnet man in der  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":6580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126,107],"tags":[],"class_list":["post-5771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avetisyan","category-glaubensfragen"],"_links":{"self":[{"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/posts\/5771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/comments?post=5771"}],"version-history":[{"count":0,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/posts\/5771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/media\/6580"}],"wp:attachment":[{"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/media?parent=5771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/categories?post=5771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/tags?post=5771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}