{"id":5568,"date":"2020-07-27T12:17:15","date_gmt":"2020-07-27T10:17:15","guid":{"rendered":"https:\/\/giessen.dakd.de\/?p=5568"},"modified":"2020-07-30T21:26:39","modified_gmt":"2020-07-30T19:26:39","slug":"bischof-serovpe-verurteilt-angriffe","status":"publish","type":"post","link":"https:\/\/bremen.dakd.de\/am\/bischof-serovpe-verurteilt-angriffe\/","title":{"rendered":"Bischof Serovp\u00e9 verurteilt Angriffe"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" src=\"http:\/\/giessen.dakd.de\/wp-content\/uploads\/2020\/03\/Bischofsvikar.jpg\" alt class=\"img-responsive wp-image-4479\"\/><\/span><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#ffac00;border-color:#ffac00;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: justify;\"><strong>Der Primas, S.E. Bischof Isakhanyan, verurteilt die j\u00fcngsten Angriffe der Streitkr\u00e4fte der Republik Aserbaidschan in den n\u00f6rdlichen Grenzgebieten Armeniens aufs sch\u00e4rfste.<\/strong><\/p>\n<p style=\"text-align: justify;\">Den bereits seit einigen Tagen andauernden Gefechten sind bereits auf beiden Seiten Opfer gefallen. Die milit\u00e4rische Aggression Aserbaidschans, gerade jetzt, in der Zeit der Corona-Pandemie, destabilisiert den ohnehin wackeligen Frieden in der\u00a0<span class=\"text_exposed_show\">Region. Der Aggressor scheut sich laut Medienberichten nicht mal davor, eine Textilfabrik in der Grenzregion zu beschie\u00dfen, die Hauptlieferant Armeniens f\u00fcr medizinische Schutzmasken ist. Armenien ist aktuell stark vom Coronavirus betroffen.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p style=\"text-align: justify;\">Der Bischof appelliert an die politischen und kirchlichen Verantwortungstr\u00e4ger in Deutschland und Europa, ihre Stimme f\u00fcr den Erhalt des Friedens in der Region zu erheben und jegliche Aggression und Angriff zu verurteilen. Es ist gewiss, dass die L\u00f6sung des Konfliktes um Arzach nur durch friedliche Verhandlungen herbeigef\u00fchrt werden sollte. Daf\u00fcr bedarf es der Solidarit\u00e4t und Unterst\u00fctzung der internationalen Gemeinschaft.<\/p>\n<p style=\"text-align: justify;\">Der Primas betet f\u00fcr die Opfer und ihre Angeh\u00f6rigen. Wenn auch Aserbaidschan einen anderen Standpunkt f\u00fcr die L\u00f6sung des Konflikts vertritt, erlaubt dies ihm nicht, diesen durch milit\u00e4rische Aggressionen auf Armenien l\u00f6sen zu wollen und sogar medizinische und humanit\u00e4re Einrichtungen anzugreifen. Der Konflikt kann n\u00e4mlich nicht milit\u00e4risch gel\u00f6st werden. Die aserbaidschanischen Streitkr\u00e4fte sollen wissen, dass die armenische Seite in der Lage ist, sowohl in der Republik Armenien, als auch in Arzach, die Grenzen zu verteidigen und ihnen schmerzhafte Verluste zuzuf\u00fcgen.<\/p>\n<p style=\"text-align: justify;\">Bischof Isakhanyan betet f\u00fcr den Frieden in der Region, und hofft sehr, dass es durch die internationale Unterst\u00fctzung eine gerechte und dauerhafte L\u00f6sung f\u00fcr Arzach gefunden werden kann, damit \u201eWaffen schweigen, Angriffe der Feinde enden und Liebe sowie Gerechtigkeit auf die Erde gepflanzt werden\u201c. Amen!<\/p>\n<p style=\"text-align: justify;\">Kanzlei der Di\u00f6zese<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":12430,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121,19],"tags":[],"class_list":["post-5568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bischof","category-dioezese"],"_links":{"self":[{"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/posts\/5568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/comments?post=5568"}],"version-history":[{"count":0,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/posts\/5568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/media\/12430"}],"wp:attachment":[{"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/media?parent=5568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/categories?post=5568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bremen.dakd.de\/am\/wp-json\/wp\/v2\/tags?post=5568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}